{"id":698,"count":72,"description":"","link":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/","name":"Agriculture","slug":"en-agriculture","taxonomy":"portfolio_category","parent":25,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Agriculture - Centrocar (Spain)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Agriculture - Centrocar (Spain)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/\" \/>\n<meta property=\"og:site_name\" content=\"Centrocar (Spain)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/en\\\/application\\\/en-agriculture\\\/\",\"url\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/en\\\/application\\\/en-agriculture\\\/\",\"name\":\"Arquivo de Agriculture - Centrocar (Spain)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/en\\\/application\\\/en-agriculture\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/en\\\/application\\\/en-agriculture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applications\",\"item\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/en\\\/application\\\/en-applications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agriculture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/#website\",\"url\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/\",\"name\":\"Centrocar (Spain)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrocar.com\\\/spain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Agriculture - Centrocar (Spain)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/","og_locale":"pt_PT","og_type":"article","og_title":"Arquivo de Agriculture - Centrocar (Spain)","og_url":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/","og_site_name":"Centrocar (Spain)","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/","url":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/","name":"Arquivo de Agriculture - Centrocar (Spain)","isPartOf":{"@id":"https:\/\/centrocar.com\/spain\/#website"},"breadcrumb":{"@id":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/centrocar.com\/spain\/en\/application\/en-agriculture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/centrocar.com\/spain\/"},{"@type":"ListItem","position":2,"name":"Applications","item":"https:\/\/centrocar.com\/spain\/en\/application\/en-applications\/"},{"@type":"ListItem","position":3,"name":"Agriculture"}]},{"@type":"WebSite","@id":"https:\/\/centrocar.com\/spain\/#website","url":"https:\/\/centrocar.com\/spain\/","name":"Centrocar (Spain)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrocar.com\/spain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/centrocar.com\/spain\/wp-json\/wp\/v2\/portfolio_category\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrocar.com\/spain\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/centrocar.com\/spain\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"up":[{"embeddable":true,"href":"https:\/\/centrocar.com\/spain\/wp-json\/wp\/v2\/portfolio_category\/25"}],"wp:post_type":[{"href":"https:\/\/centrocar.com\/spain\/wp-json\/wp\/v2\/avada_portfolio?portfolio_category=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}